{"id":47,"count":263,"description":"","link":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/","name":"Administraci\u00f3n General del Estado.","slug":"administracion-general-del-estado","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualidad Oposiciones del estado - Noticas de oposiciones por Academia Emplea-te<\/title>\n<meta name=\"description\" content=\"\u00daltimas noticias sobre ofertas, ex\u00e1menes y convocatorias de las oposiciones de la administraci\u00f3n general del estado. \u00a1Inf\u00f3rmate ahora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualidad Oposiciones del estado - Noticas de oposiciones por Academia Emplea-te\" \/>\n<meta property=\"og:description\" content=\"\u00daltimas noticias sobre ofertas, ex\u00e1menes y convocatorias de las oposiciones de la administraci\u00f3n general del estado. \u00a1Inf\u00f3rmate ahora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticas de oposiciones por Academia Emplea-te\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Emplea_Te\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/categoria\\\/administracion-general-del-estado\\\/\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/categoria\\\/administracion-general-del-estado\\\/\",\"name\":\"Actualidad Oposiciones del estado - Noticas de oposiciones por Academia Emplea-te\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#website\"},\"description\":\"\u00daltimas noticias sobre ofertas, ex\u00e1menes y convocatorias de las oposiciones de la administraci\u00f3n general del estado. \u00a1Inf\u00f3rmate ahora!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/categoria\\\/administracion-general-del-estado\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/categoria\\\/administracion-general-del-estado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias Oposiciones\",\"item\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Administraci\u00f3n General del Estado.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#website\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/\",\"name\":\"Noticas de oposiciones por Academia Emplea-te\",\"description\":\"Toda la actualidad de las ofertas y convocatorias.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#organization\",\"name\":\"Academia de oposiciones Empl\u00e9ate\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/empleate.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/empleate.jpg\",\"width\":250,\"height\":150,\"caption\":\"Academia de oposiciones Empl\u00e9ate\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AcademiaEmpleate\\\/\",\"https:\\\/\\\/x.com\\\/Emplea_Te\",\"https:\\\/\\\/www.instagram.com\\\/academia_empleate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualidad Oposiciones del estado - Noticas de oposiciones por Academia Emplea-te","description":"\u00daltimas noticias sobre ofertas, ex\u00e1menes y convocatorias de las oposiciones de la administraci\u00f3n general del estado. \u00a1Inf\u00f3rmate ahora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/","og_locale":"es_ES","og_type":"article","og_title":"Actualidad Oposiciones del estado - Noticas de oposiciones por Academia Emplea-te","og_description":"\u00daltimas noticias sobre ofertas, ex\u00e1menes y convocatorias de las oposiciones de la administraci\u00f3n general del estado. \u00a1Inf\u00f3rmate ahora!","og_url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/","og_site_name":"Noticas de oposiciones por Academia Emplea-te","twitter_card":"summary_large_image","twitter_site":"@Emplea_Te","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/","name":"Actualidad Oposiciones del estado - Noticas de oposiciones por Academia Emplea-te","isPartOf":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#website"},"description":"\u00daltimas noticias sobre ofertas, ex\u00e1menes y convocatorias de las oposiciones de la administraci\u00f3n general del estado. \u00a1Inf\u00f3rmate ahora!","breadcrumb":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/administracion-general-del-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias Oposiciones","item":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/"},{"@type":"ListItem","position":2,"name":"Administraci\u00f3n General del Estado."}]},{"@type":"WebSite","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#website","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/","name":"Noticas de oposiciones por Academia Emplea-te","description":"Toda la actualidad de las ofertas y convocatorias.","publisher":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#organization","name":"Academia de oposiciones Empl\u00e9ate","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#\/schema\/logo\/image\/","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-content\/uploads\/2019\/04\/empleate.jpg","contentUrl":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-content\/uploads\/2019\/04\/empleate.jpg","width":250,"height":150,"caption":"Academia de oposiciones Empl\u00e9ate"},"image":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AcademiaEmpleate\/","https:\/\/x.com\/Emplea_Te","https:\/\/www.instagram.com\/academia_empleate\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/categories\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/posts?categories=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}