{"id":13490,"date":"2024-11-05T10:08:10","date_gmt":"2024-11-05T09:08:10","guid":{"rendered":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/?p=13490"},"modified":"2024-11-05T10:08:10","modified_gmt":"2024-11-05T09:08:10","slug":"ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio","status":"publish","type":"post","link":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/","title":{"rendered":"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio."},"content":{"rendered":"<p>Se publica en el BOCM de hoy, d\u00eda 5 de noviembre de 2024, la Resoluci\u00f3n por la que se hace p\u00fablica la relaci\u00f3n definitiva de aspirantes admitidos y excluidos en proceso selectivo convocado para cubrir 5 plazas de T\u00e9cnico de Gesti\u00f3n A2\u00a0 (BOE 05\/06\/2024) por turno libre.<\/p>\n<p><a href=\"https:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2024\/11\/05\/BOCM-20241105-94.PDF\" target=\"_blank\" rel=\"noopener\"><strong>La relaci\u00f3n de aspirantes excluidos y la causa de exclusi\u00f3n puede consultarse en esta Resoluci\u00f3n.\u00a0<\/strong><\/a><\/p>\n<p>Los aspirantes admitidos quedan convocados para la realizaci\u00f3n del primer ejercicio de la fase de oposici\u00f3n para el pr\u00f3ximo d\u00eda 18\/11\/2024 en a las 12:00 horas en el Centro de formaci\u00f3n Marcelino Camacho.<\/p>\n<p>\u00a1\u00c1nimo!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se publica en el BOCM de hoy, d\u00eda 5 de noviembre de 2024, la Resoluci\u00f3n por la que se hace p\u00fablica la relaci\u00f3n definitiva de aspirantes admitidos y excluidos en proceso selectivo convocado para cubrir 5 plazas de T\u00e9cnico de Gesti\u00f3n A2\u00a0 (BOE 05\/06\/2024) por turno libre. La relaci\u00f3n de aspirantes excluidos y la causa &hellip; <a href=\"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAyuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115,109],"tags":[49,71,103,87],"class_list":["post-13490","post","type-post","status-publish","format-standard","hentry","category-convocatoria-ayuntamientos","category-oposiciones-madrid","tag-convocatorias-de-oposiciones","tag-fecha-examenes","tag-informacion-procesos-selectivos","tag-listados-definitivos-de-aspirantes-admitidos-y-excluidos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ayto. de San Sebasti\u00e1n de los Reyes. Convocatoria empleo p\u00fablico<\/title>\n<meta name=\"description\" content=\"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ayto. de San Sebasti\u00e1n de los Reyes. Convocatoria empleo p\u00fablico\" \/>\n<meta property=\"og:description\" content=\"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticas de oposiciones por Academia Emplea-te\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AcademiaEmpleate\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-05T09:08:10+00:00\" \/>\n<meta name=\"author\" content=\"Empleate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Emplea_Te\" \/>\n<meta name=\"twitter:site\" content=\"@Emplea_Te\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Empleate\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/\"},\"author\":{\"name\":\"Empleate\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#\\\/schema\\\/person\\\/d1bc587e1af2b95e9c32aba1795509a6\"},\"headline\":\"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.\",\"datePublished\":\"2024-11-05T09:08:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/\"},\"wordCount\":134,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#organization\"},\"keywords\":[\"Convocatoria\",\"Fecha ex\u00e1menes\",\"Informaci\u00f3n procesos selectivos\",\"Listados Definitivos de aspirantes admitidos y excluidos\"],\"articleSection\":[\"CONVOCATORIA AYUNTAMIENTOS\",\"Oposiciones Madrid.\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/\",\"name\":\"Ayto. de San Sebasti\u00e1n de los Reyes. Convocatoria empleo p\u00fablico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#website\"},\"datePublished\":\"2024-11-05T09:08:10+00:00\",\"description\":\"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias Oposiciones\",\"item\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones Madrid.\",\"item\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/categoria\\\/oposiciones-madrid\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#website\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/\",\"name\":\"Noticas de oposiciones por Academia Emplea-te\",\"description\":\"Toda la actualidad de las ofertas y convocatorias.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#organization\",\"name\":\"Academia de oposiciones Empl\u00e9ate\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/empleate.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/empleate.jpg\",\"width\":250,\"height\":150,\"caption\":\"Academia de oposiciones Empl\u00e9ate\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AcademiaEmpleate\\\/\",\"https:\\\/\\\/x.com\\\/Emplea_Te\",\"https:\\\/\\\/www.instagram.com\\\/academia_empleate\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emplea-te.com\\\/noticias-oposiciones\\\/#\\\/schema\\\/person\\\/d1bc587e1af2b95e9c32aba1795509a6\",\"name\":\"Empleate\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ayto. de San Sebasti\u00e1n de los Reyes. Convocatoria empleo p\u00fablico","description":"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/","og_locale":"es_ES","og_type":"article","og_title":"Ayto. de San Sebasti\u00e1n de los Reyes. Convocatoria empleo p\u00fablico","og_description":"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.","og_url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/","og_site_name":"Noticas de oposiciones por Academia Emplea-te","article_publisher":"https:\/\/www.facebook.com\/AcademiaEmpleate\/","article_published_time":"2024-11-05T09:08:10+00:00","author":"Empleate","twitter_card":"summary_large_image","twitter_creator":"@Emplea_Te","twitter_site":"@Emplea_Te","twitter_misc":{"Escrito por":"Empleate","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/#article","isPartOf":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/"},"author":{"name":"Empleate","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#\/schema\/person\/d1bc587e1af2b95e9c32aba1795509a6"},"headline":"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.","datePublished":"2024-11-05T09:08:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/"},"wordCount":134,"publisher":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#organization"},"keywords":["Convocatoria","Fecha ex\u00e1menes","Informaci\u00f3n procesos selectivos","Listados Definitivos de aspirantes admitidos y excluidos"],"articleSection":["CONVOCATORIA AYUNTAMIENTOS","Oposiciones Madrid."],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/","name":"Ayto. de San Sebasti\u00e1n de los Reyes. Convocatoria empleo p\u00fablico","isPartOf":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#website"},"datePublished":"2024-11-05T09:08:10+00:00","description":"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio.","breadcrumb":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/ayuntamiento-de-san-sebastian-de-los-reyes-5-plazas-convocadas-tecnico-de-gestion-a2-relacion-definitiva-aspirantes-admitidos-y-excluidos-y-fecha-realizacion-primer-ejercicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias Oposiciones","item":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/"},{"@type":"ListItem","position":2,"name":"Oposiciones Madrid.","item":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/categoria\/oposiciones-madrid\/"},{"@type":"ListItem","position":3,"name":"Ayuntamiento de San Sebasti\u00e1n de los Reyes. 5 plazas convocadas T\u00e9cnico de Gesti\u00f3n A2. Relaci\u00f3n definitiva aspirantes admitidos y excluidos y fecha realizaci\u00f3n primer ejercicio."}]},{"@type":"WebSite","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#website","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/","name":"Noticas de oposiciones por Academia Emplea-te","description":"Toda la actualidad de las ofertas y convocatorias.","publisher":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#organization","name":"Academia de oposiciones Empl\u00e9ate","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#\/schema\/logo\/image\/","url":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-content\/uploads\/2019\/04\/empleate.jpg","contentUrl":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-content\/uploads\/2019\/04\/empleate.jpg","width":250,"height":150,"caption":"Academia de oposiciones Empl\u00e9ate"},"image":{"@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AcademiaEmpleate\/","https:\/\/x.com\/Emplea_Te","https:\/\/www.instagram.com\/academia_empleate\/"]},{"@type":"Person","@id":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/#\/schema\/person\/d1bc587e1af2b95e9c32aba1795509a6","name":"Empleate"}]}},"_links":{"self":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/posts\/13490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/comments?post=13490"}],"version-history":[{"count":1,"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/posts\/13490\/revisions"}],"predecessor-version":[{"id":13491,"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/posts\/13490\/revisions\/13491"}],"wp:attachment":[{"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/media?parent=13490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/categories?post=13490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emplea-te.com\/noticias-oposiciones\/wp-json\/wp\/v2\/tags?post=13490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}